{"id":37,"count":1,"description":"","link":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/","name":"Actualit\u00e9s","slug":"actualites","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Actualit\u00e9s Archives - Fortress Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualit\u00e9s Archives - Fortress Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/\" \/>\n<meta property=\"og:site_name\" content=\"Fortress Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/\",\"url\":\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/\",\"name\":\"Actualit\u00e9s Archives - Fortress Europe\",\"isPartOf\":{\"@id\":\"https:\/\/fortresseurope.com\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fortresseurope.com\/fr\/category\/actualites\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fortresseurope.com\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fortresseurope.com\/fr\/#website\",\"url\":\"https:\/\/fortresseurope.com\/fr\/\",\"name\":\"Fortress Europe\",\"description\":\"Stabilisation Products\",\"publisher\":{\"@id\":\"https:\/\/fortresseurope.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fortresseurope.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fortresseurope.com\/fr\/#organization\",\"name\":\"Fortress Europe\",\"url\":\"https:\/\/fortresseurope.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/fortresseurope.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fortresseurope.com\/wp-content\/uploads\/2024\/04\/fortresseurope.svg\",\"contentUrl\":\"https:\/\/fortresseurope.com\/wp-content\/uploads\/2024\/04\/fortresseurope.svg\",\"width\":1566,\"height\":456,\"caption\":\"Fortress Europe\"},\"image\":{\"@id\":\"https:\/\/fortresseurope.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualit\u00e9s Archives - Fortress Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/","og_locale":"fr_FR","og_type":"article","og_title":"Actualit\u00e9s Archives - Fortress Europe","og_url":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/","og_site_name":"Fortress Europe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/","url":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/","name":"Actualit\u00e9s Archives - Fortress Europe","isPartOf":{"@id":"https:\/\/fortresseurope.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/fortresseurope.com\/fr\/category\/actualites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fortresseurope.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/fortresseurope.com\/fr\/#website","url":"https:\/\/fortresseurope.com\/fr\/","name":"Fortress Europe","description":"Stabilisation Products","publisher":{"@id":"https:\/\/fortresseurope.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fortresseurope.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fortresseurope.com\/fr\/#organization","name":"Fortress Europe","url":"https:\/\/fortresseurope.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fortresseurope.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fortresseurope.com\/wp-content\/uploads\/2024\/04\/fortresseurope.svg","contentUrl":"https:\/\/fortresseurope.com\/wp-content\/uploads\/2024\/04\/fortresseurope.svg","width":1566,"height":456,"caption":"Fortress Europe"},"image":{"@id":"https:\/\/fortresseurope.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fortresseurope.com\/fr\/wp-json\/wp\/v2\/categories\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fortresseurope.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fortresseurope.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fortresseurope.com\/fr\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}